{"id":12682,"date":"2025-12-18T13:55:57","date_gmt":"2025-12-18T21:55:57","guid":{"rendered":"https:\/\/salesforceventures.com\/?post_type=companies&#038;p=12682"},"modified":"2025-12-19T05:46:15","modified_gmt":"2025-12-19T13:46:15","slug":"black-forest-labs","status":"publish","type":"companies","link":"https:\/\/salesforceventures.com\/ja\/companies\/black-forest-labs\/","title":{"rendered":"Black Forest Labs"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Leading frontier AI research lab, continuously building the most advanced technology that shapes the visual understanding of the world.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leading frontier AI research lab, continuously building the most advanced technology that shapes the visual understanding of the world.<\/p>\n","protected":false},"author":59,"featured_media":0,"template":"","company_status":[776,46],"company_type":[109],"company_region":[],"coauthors":[105],"class_list":["post-12682","companies","type-companies","status-publish","hentry","company_status-active","company_status-spotlight","company_type-generative-ai"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Black Forest Labs | Salesforce Ventures<\/title>\n<meta name=\"description\" content=\"Salesforce Ventures provides the most enterprising founders with patient capital, coveted community, and privileged access to the resources they need to build industry-defining companies.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salesforceventures.com\/companies\/black-forest-labs\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Black Forest Labs\" \/>\n<meta property=\"og:description\" content=\"Salesforce Ventures provides the most enterprising founders with patient capital, coveted community, and privileged access to the resources they need to build industry-defining companies.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salesforceventures.com\/companies\/black-forest-labs\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce Ventures\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-19T13:46:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SalesforceVC\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Adam Mills\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/black-forest-labs\\\/\",\"url\":\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/black-forest-labs\\\/\",\"name\":\"Black Forest Labs | Salesforce Ventures\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/#website\"},\"datePublished\":\"2025-12-18T21:55:57+00:00\",\"dateModified\":\"2025-12-19T13:46:15+00:00\",\"description\":\"Salesforce Ventures provides the most enterprising founders with patient capital, coveted community, and privileged access to the resources they need to build industry-defining companies.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/black-forest-labs\\\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/black-forest-labs\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/black-forest-labs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/salesforceventures.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Companies\",\"item\":\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Black Forest Labs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/#website\",\"url\":\"https:\\\/\\\/salesforceventures.com\\\/\",\"name\":\"Salesforce Ventures\",\"description\":\"For the Most Enterprising Founders\",\"publisher\":{\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salesforceventures.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/#organization\",\"name\":\"Salesforce Ventures\",\"url\":\"https:\\\/\\\/salesforceventures.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salesforceventures.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Salesforce-Ventures-Logo-1.png\",\"contentUrl\":\"https:\\\/\\\/salesforceventures.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Salesforce-Ventures-Logo-1.png\",\"width\":2979,\"height\":1050,\"caption\":\"Salesforce Ventures\"},\"image\":{\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SalesforceVC\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/salesforce-ventures\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Black Forest Labs | Salesforce Ventures","description":"Salesforce Ventures provides the most enterprising founders with patient capital, coveted community, and privileged access to the resources they need to build industry-defining companies.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salesforceventures.com\/companies\/black-forest-labs\/","og_locale":"ja_JP","og_type":"article","og_title":"Black Forest Labs","og_description":"Salesforce Ventures provides the most enterprising founders with patient capital, coveted community, and privileged access to the resources they need to build industry-defining companies.","og_url":"https:\/\/salesforceventures.com\/companies\/black-forest-labs\/","og_site_name":"Salesforce Ventures","article_modified_time":"2025-12-19T13:46:15+00:00","twitter_card":"summary_large_image","twitter_site":"@SalesforceVC","twitter_misc":{"Est. reading time":"1 minute","Written by":"Adam Mills"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/salesforceventures.com\/companies\/black-forest-labs\/","url":"https:\/\/salesforceventures.com\/companies\/black-forest-labs\/","name":"Black Forest Labs | Salesforce Ventures","isPartOf":{"@id":"https:\/\/salesforceventures.com\/#website"},"datePublished":"2025-12-18T21:55:57+00:00","dateModified":"2025-12-19T13:46:15+00:00","description":"Salesforce Ventures provides the most enterprising founders with patient capital, coveted community, and privileged access to the resources they need to build industry-defining companies.","breadcrumb":{"@id":"https:\/\/salesforceventures.com\/companies\/black-forest-labs\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salesforceventures.com\/companies\/black-forest-labs\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/salesforceventures.com\/companies\/black-forest-labs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/salesforceventures.com\/"},{"@type":"ListItem","position":2,"name":"Companies","item":"https:\/\/salesforceventures.com\/companies\/"},{"@type":"ListItem","position":3,"name":"Black Forest Labs"}]},{"@type":"WebSite","@id":"https:\/\/salesforceventures.com\/#website","url":"https:\/\/salesforceventures.com\/","name":"Salesforce Ventures","description":"For the Most Enterprising Founders","publisher":{"@id":"https:\/\/salesforceventures.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salesforceventures.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/salesforceventures.com\/#organization","name":"Salesforce Ventures","url":"https:\/\/salesforceventures.com\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/salesforceventures.com\/#\/schema\/logo\/image\/","url":"https:\/\/salesforceventures.com\/wp-content\/uploads\/2022\/05\/Salesforce-Ventures-Logo-1.png","contentUrl":"https:\/\/salesforceventures.com\/wp-content\/uploads\/2022\/05\/Salesforce-Ventures-Logo-1.png","width":2979,"height":1050,"caption":"Salesforce Ventures"},"image":{"@id":"https:\/\/salesforceventures.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SalesforceVC","https:\/\/www.linkedin.com\/company\/salesforce-ventures\/"]}]}},"jetpack_sharing_enabled":true,"company_name":[],"logo":[],"logo_white":[],"leadership":[],"ticker":[],"market":[],"current_status":[],"company_link":[],"facebook_link":[],"twitter_link":[],"linkedin_link":[],"_links":{"self":[{"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/companies\/12682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/companies"}],"about":[{"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/types\/companies"}],"author":[{"embeddable":true,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/users\/59"}],"version-history":[{"count":2,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/companies\/12682\/revisions"}],"predecessor-version":[{"id":12687,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/companies\/12682\/revisions\/12687"}],"wp:attachment":[{"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/media?parent=12682"}],"wp:term":[{"taxonomy":"company_status","embeddable":true,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/company_status?post=12682"},{"taxonomy":"company_type","embeddable":true,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/company_type?post=12682"},{"taxonomy":"company_region","embeddable":true,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/company_region?post=12682"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/coauthors?post=12682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}