{"id":1529,"date":"2022-05-04T10:40:08","date_gmt":"2022-05-04T17:40:08","guid":{"rendered":"https:\/\/salesforce.reaktivdev.com\/companies\/1password\/"},"modified":"2023-10-23T16:09:00","modified_gmt":"2023-10-23T23:09:00","slug":"1password","status":"publish","type":"companies","link":"https:\/\/salesforceventures.com\/ja\/companies\/1password\/","title":{"rendered":"1Password"},"content":{"rendered":"<p>1Password is a privacy-focused password manager that keeps you safe online. 1Password is the world\u2019s most-loved password manager. By combining industry-leading security and award-winning design, the company provides private, secure, and user-friendly password management to businesses and consumers globally.<\/p>\n<p>1Password is the developer of a secure, scalable, and easy-to-use password manager that\u2019s trusted by the world\u2019s leading companies.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1Password is a privacy-focused password manager that keeps you safe online. 1Password is the world\u2019s most-loved password manager. By combining industry-leading security and award-winning design, the company provides private, secure, and user-friendly password management to businesses and consumers globally. 1Password is the developer of a secure, scalable, and easy-to-use password manager that\u2019s trusted by the<\/p>\n","protected":false},"author":56,"featured_media":1730,"template":"","company_status":[776,46],"company_type":[45,116],"company_region":[772],"coauthors":[67],"class_list":["post-1529","companies","type-companies","status-publish","has-post-thumbnail","hentry","company_status-active","company_status-spotlight","company_type-security","company_type-slack-fund","company_region-amer"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>1Password | Salesforce Ventures<\/title>\n<meta name=\"description\" content=\"Salesforce Ventures provides the most enterprising founders with patient capital, coveted community, and privileged access to the resources they need to build industry-defining companies.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salesforceventures.com\/companies\/1password\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1Password\" \/>\n<meta property=\"og:description\" content=\"Salesforce Ventures provides the most enterprising founders with patient capital, coveted community, and privileged access to the resources they need to build industry-defining companies.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salesforceventures.com\/companies\/1password\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce Ventures\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-23T23:09:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/salesforceventures.com\/wp-content\/uploads\/2022\/05\/1Password-Founders.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1457\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SalesforceVC\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Alexa Makreas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/1password\\\/\",\"url\":\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/1password\\\/\",\"name\":\"1Password | Salesforce Ventures\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/1password\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/1password\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/salesforceventures.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/1Password-Founders.jpg\",\"datePublished\":\"2022-05-04T17:40:08+00:00\",\"dateModified\":\"2023-10-23T23:09:00+00:00\",\"description\":\"Salesforce Ventures provides the most enterprising founders with patient capital, coveted community, and privileged access to the resources they need to build industry-defining companies.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/1password\\\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/1password\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/1password\\\/#primaryimage\",\"url\":\"https:\\\/\\\/salesforceventures.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/1Password-Founders.jpg\",\"contentUrl\":\"https:\\\/\\\/salesforceventures.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/1Password-Founders.jpg\",\"width\":2400,\"height\":1457},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/1password\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/salesforceventures.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Companies\",\"item\":\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1Password\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/#website\",\"url\":\"https:\\\/\\\/salesforceventures.com\\\/\",\"name\":\"Salesforce Ventures\",\"description\":\"For the Most Enterprising Founders\",\"publisher\":{\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salesforceventures.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/#organization\",\"name\":\"Salesforce Ventures\",\"url\":\"https:\\\/\\\/salesforceventures.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salesforceventures.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Salesforce-Ventures-Logo-1.png\",\"contentUrl\":\"https:\\\/\\\/salesforceventures.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Salesforce-Ventures-Logo-1.png\",\"width\":2979,\"height\":1050,\"caption\":\"Salesforce Ventures\"},\"image\":{\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SalesforceVC\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/salesforce-ventures\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"1Password | Salesforce Ventures","description":"Salesforce Ventures provides the most enterprising founders with patient capital, coveted community, and privileged access to the resources they need to build industry-defining companies.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salesforceventures.com\/companies\/1password\/","og_locale":"ja_JP","og_type":"article","og_title":"1Password","og_description":"Salesforce Ventures provides the most enterprising founders with patient capital, coveted community, and privileged access to the resources they need to build industry-defining companies.","og_url":"https:\/\/salesforceventures.com\/companies\/1password\/","og_site_name":"Salesforce Ventures","article_modified_time":"2023-10-23T23:09:00+00:00","og_image":[{"width":2400,"height":1457,"url":"https:\/\/salesforceventures.com\/wp-content\/uploads\/2022\/05\/1Password-Founders.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@SalesforceVC","twitter_misc":{"Est. reading time":"1 minute","Written by":"Alexa Makreas"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/salesforceventures.com\/companies\/1password\/","url":"https:\/\/salesforceventures.com\/companies\/1password\/","name":"1Password | Salesforce Ventures","isPartOf":{"@id":"https:\/\/salesforceventures.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/salesforceventures.com\/companies\/1password\/#primaryimage"},"image":{"@id":"https:\/\/salesforceventures.com\/companies\/1password\/#primaryimage"},"thumbnailUrl":"https:\/\/salesforceventures.com\/wp-content\/uploads\/2022\/05\/1Password-Founders.jpg","datePublished":"2022-05-04T17:40:08+00:00","dateModified":"2023-10-23T23:09:00+00:00","description":"Salesforce Ventures provides the most enterprising founders with patient capital, coveted community, and privileged access to the resources they need to build industry-defining companies.","breadcrumb":{"@id":"https:\/\/salesforceventures.com\/companies\/1password\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salesforceventures.com\/companies\/1password\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/salesforceventures.com\/companies\/1password\/#primaryimage","url":"https:\/\/salesforceventures.com\/wp-content\/uploads\/2022\/05\/1Password-Founders.jpg","contentUrl":"https:\/\/salesforceventures.com\/wp-content\/uploads\/2022\/05\/1Password-Founders.jpg","width":2400,"height":1457},{"@type":"BreadcrumbList","@id":"https:\/\/salesforceventures.com\/companies\/1password\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/salesforceventures.com\/"},{"@type":"ListItem","position":2,"name":"Companies","item":"https:\/\/salesforceventures.com\/companies\/"},{"@type":"ListItem","position":3,"name":"1Password"}]},{"@type":"WebSite","@id":"https:\/\/salesforceventures.com\/#website","url":"https:\/\/salesforceventures.com\/","name":"Salesforce Ventures","description":"For the Most Enterprising Founders","publisher":{"@id":"https:\/\/salesforceventures.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salesforceventures.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/salesforceventures.com\/#organization","name":"Salesforce Ventures","url":"https:\/\/salesforceventures.com\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/salesforceventures.com\/#\/schema\/logo\/image\/","url":"https:\/\/salesforceventures.com\/wp-content\/uploads\/2022\/05\/Salesforce-Ventures-Logo-1.png","contentUrl":"https:\/\/salesforceventures.com\/wp-content\/uploads\/2022\/05\/Salesforce-Ventures-Logo-1.png","width":2979,"height":1050,"caption":"Salesforce Ventures"},"image":{"@id":"https:\/\/salesforceventures.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SalesforceVC","https:\/\/www.linkedin.com\/company\/salesforce-ventures\/"]}]}},"jetpack_sharing_enabled":true,"company_name":[],"logo":[],"logo_white":[],"leadership":[],"ticker":[],"market":[],"current_status":[],"company_link":[],"facebook_link":[],"twitter_link":[],"linkedin_link":[],"_links":{"self":[{"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/companies\/1529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/companies"}],"about":[{"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/types\/companies"}],"author":[{"embeddable":true,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/users\/56"}],"version-history":[{"count":2,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/companies\/1529\/revisions"}],"predecessor-version":[{"id":4719,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/companies\/1529\/revisions\/4719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/media\/1730"}],"wp:attachment":[{"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/media?parent=1529"}],"wp:term":[{"taxonomy":"company_status","embeddable":true,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/company_status?post=1529"},{"taxonomy":"company_type","embeddable":true,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/company_type?post=1529"},{"taxonomy":"company_region","embeddable":true,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/company_region?post=1529"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/coauthors?post=1529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}