{"id":1709,"date":"2022-05-04T10:40:17","date_gmt":"2022-05-04T14:40:17","guid":{"rendered":"https:\/\/salesforce.reaktivdev.com\/companies\/upward\/"},"modified":"2024-11-21T05:08:29","modified_gmt":"2024-11-21T13:08:29","slug":"upward","status":"publish","type":"companies","link":"https:\/\/salesforceventures.com\/ja\/companies\/upward\/","title":{"rendered":"Upward"},"content":{"rendered":"<p>Since its founding, UPWARD has been involved in the construction of many commercial systems as a top-class system integrator in Japan that specializes in location information and Web technologies based on open source. In the last few years, as everyone has been able to utilize location information on mobile devices, we focused on the potential of the cloud from an early stage and entered into a capital tie-up with Salesforce.com, the world&#8217;s No. 1 cloud CRM. We have started to provide &#8220;UPWARD&#8221; service that fully links CRM and location information. Currently, UPWARD is being introduced by more than 260 companies as a sales support service for mobile workers.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Since its founding, UPWARD has been involved in the construction of many commercial systems as a top-class system integrator in Japan that specializes in location information and Web technologies based on open source. In the last few years, as everyone has been able to utilize location information on mobile devices, we focused on the potential<\/p>\n","protected":false},"author":56,"featured_media":0,"template":"","company_status":[776],"company_type":[],"company_region":[774],"coauthors":[67],"class_list":["post-1709","companies","type-companies","status-publish","hentry","company_status-active","company_region-apac"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Upward | Salesforce Ventures<\/title>\n<meta name=\"description\" content=\"Salesforce Ventures provides the most enterprising founders with patient capital, coveted community, and privileged access to the resources they need to build industry-defining companies.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salesforceventures.com\/companies\/upward\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Upward\" \/>\n<meta property=\"og:description\" content=\"Salesforce Ventures provides the most enterprising founders with patient capital, coveted community, and privileged access to the resources they need to build industry-defining companies.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salesforceventures.com\/companies\/upward\/\" \/>\n<meta property=\"og:site_name\" content=\"Salesforce Ventures\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-21T13:08:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SalesforceVC\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Alexa Makreas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/upward\\\/\",\"url\":\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/upward\\\/\",\"name\":\"Upward | Salesforce Ventures\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/#website\"},\"datePublished\":\"2022-05-04T14:40:17+00:00\",\"dateModified\":\"2024-11-21T13:08:29+00:00\",\"description\":\"Salesforce Ventures provides the most enterprising founders with patient capital, coveted community, and privileged access to the resources they need to build industry-defining companies.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/upward\\\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/upward\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/upward\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/salesforceventures.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Companies\",\"item\":\"https:\\\/\\\/salesforceventures.com\\\/companies\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Upward\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/#website\",\"url\":\"https:\\\/\\\/salesforceventures.com\\\/\",\"name\":\"Salesforce Ventures\",\"description\":\"For the Most Enterprising Founders\",\"publisher\":{\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/salesforceventures.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/#organization\",\"name\":\"Salesforce Ventures\",\"url\":\"https:\\\/\\\/salesforceventures.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/salesforceventures.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Salesforce-Ventures-Logo-1.png\",\"contentUrl\":\"https:\\\/\\\/salesforceventures.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Salesforce-Ventures-Logo-1.png\",\"width\":2979,\"height\":1050,\"caption\":\"Salesforce Ventures\"},\"image\":{\"@id\":\"https:\\\/\\\/salesforceventures.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/SalesforceVC\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/salesforce-ventures\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Upward | Salesforce Ventures","description":"Salesforce Ventures provides the most enterprising founders with patient capital, coveted community, and privileged access to the resources they need to build industry-defining companies.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salesforceventures.com\/companies\/upward\/","og_locale":"ja_JP","og_type":"article","og_title":"Upward","og_description":"Salesforce Ventures provides the most enterprising founders with patient capital, coveted community, and privileged access to the resources they need to build industry-defining companies.","og_url":"https:\/\/salesforceventures.com\/companies\/upward\/","og_site_name":"Salesforce Ventures","article_modified_time":"2024-11-21T13:08:29+00:00","twitter_card":"summary_large_image","twitter_site":"@SalesforceVC","twitter_misc":{"Est. reading time":"1 minute","Written by":"Alexa Makreas"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/salesforceventures.com\/companies\/upward\/","url":"https:\/\/salesforceventures.com\/companies\/upward\/","name":"Upward | Salesforce Ventures","isPartOf":{"@id":"https:\/\/salesforceventures.com\/#website"},"datePublished":"2022-05-04T14:40:17+00:00","dateModified":"2024-11-21T13:08:29+00:00","description":"Salesforce Ventures provides the most enterprising founders with patient capital, coveted community, and privileged access to the resources they need to build industry-defining companies.","breadcrumb":{"@id":"https:\/\/salesforceventures.com\/companies\/upward\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salesforceventures.com\/companies\/upward\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/salesforceventures.com\/companies\/upward\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/salesforceventures.com\/"},{"@type":"ListItem","position":2,"name":"Companies","item":"https:\/\/salesforceventures.com\/companies\/"},{"@type":"ListItem","position":3,"name":"Upward"}]},{"@type":"WebSite","@id":"https:\/\/salesforceventures.com\/#website","url":"https:\/\/salesforceventures.com\/","name":"Salesforce Ventures","description":"For the Most Enterprising Founders","publisher":{"@id":"https:\/\/salesforceventures.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salesforceventures.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/salesforceventures.com\/#organization","name":"Salesforce Ventures","url":"https:\/\/salesforceventures.com\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/salesforceventures.com\/#\/schema\/logo\/image\/","url":"https:\/\/salesforceventures.com\/wp-content\/uploads\/2022\/05\/Salesforce-Ventures-Logo-1.png","contentUrl":"https:\/\/salesforceventures.com\/wp-content\/uploads\/2022\/05\/Salesforce-Ventures-Logo-1.png","width":2979,"height":1050,"caption":"Salesforce Ventures"},"image":{"@id":"https:\/\/salesforceventures.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/SalesforceVC","https:\/\/www.linkedin.com\/company\/salesforce-ventures\/"]}]}},"jetpack_sharing_enabled":true,"company_name":[],"logo":[],"logo_white":[],"leadership":[],"ticker":[],"market":[],"current_status":[],"company_link":[],"facebook_link":[],"twitter_link":[],"linkedin_link":[],"_links":{"self":[{"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/companies\/1709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/companies"}],"about":[{"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/types\/companies"}],"author":[{"embeddable":true,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/users\/56"}],"version-history":[{"count":1,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/companies\/1709\/revisions"}],"predecessor-version":[{"id":6482,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/companies\/1709\/revisions\/6482"}],"wp:attachment":[{"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/media?parent=1709"}],"wp:term":[{"taxonomy":"company_status","embeddable":true,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/company_status?post=1709"},{"taxonomy":"company_type","embeddable":true,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/company_type?post=1709"},{"taxonomy":"company_region","embeddable":true,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/company_region?post=1709"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/salesforceventures.com\/ja\/wp-json\/wp\/v2\/coauthors?post=1709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}